{"id":15956,"date":"2023-02-16T15:57:44","date_gmt":"2023-02-16T14:57:44","guid":{"rendered":"https:\/\/franchiseoncloud.fr\/?p=15956"},"modified":"2025-11-13T11:26:38","modified_gmt":"2025-11-13T10:26:38","slug":"franchise-on-cloud-retrospective-2022","status":"publish","type":"post","link":"https:\/\/cerca.io\/es\/franquicia-en-la-nube-retrospectiva-2022\/","title":{"rendered":"Cerca ex Franquicia en la Nube - Una mirada retrospectiva a nuestro a\u00f1o 2022"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"15956\" class=\"elementor elementor-15956\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f90adb0 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"f90adb0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8b9baa8\" data-id=\"8b9baa8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2233089 elementor-widget elementor-widget-image\" data-id=\"2233089\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"2049\" height=\"720\" src=\"https:\/\/cerca.io\/wp-content\/uploads\/2025\/08\/ES_Visuel-article-3.png\" class=\"attachment-full size-full wp-image-19869\" alt=\"Cerca ex franquicia en la nube\" srcset=\"https:\/\/cerca.io\/wp-content\/uploads\/2025\/08\/ES_Visuel-article-3.png 2049w, https:\/\/cerca.io\/wp-content\/uploads\/2025\/08\/ES_Visuel-article-3-300x105.png 300w, https:\/\/cerca.io\/wp-content\/uploads\/2025\/08\/ES_Visuel-article-3-1024x360.png 1024w, https:\/\/cerca.io\/wp-content\/uploads\/2025\/08\/ES_Visuel-article-3-768x270.png 768w, https:\/\/cerca.io\/wp-content\/uploads\/2025\/08\/ES_Visuel-article-3-1536x540.png 1536w, https:\/\/cerca.io\/wp-content\/uploads\/2025\/08\/ES_Visuel-article-3-18x6.png 18w\" sizes=\"(max-width: 2049px) 100vw, 2049px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-db7b8e8 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"db7b8e8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-80d90d8\" data-id=\"80d90d8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-94eced2 elementor-widget elementor-widget-text-editor\" data-id=\"94eced2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>Un gran a\u00f1o acaba de terminar, y tenemos muchos proyectos emocionantes para 2023. Antes de lanzarnos con toda nuestra ambici\u00f3n en este nuevo a\u00f1o, creemos que siempre es bueno tomar perspectiva sobre el a\u00f1o que ha pasado. \u00a1Vamos a hacer una retrospectiva de 2022!<\/b><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0e019a3 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"0e019a3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cbd04ea\" data-id=\"cbd04ea\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3e4cb55 elementor-widget elementor-widget-heading\" data-id=\"3e4cb55\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Nuestro a\u00f1o en cifras\u00a0<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d9d1d5d elementor-widget elementor-widget-text-editor\" data-id=\"d9d1d5d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\"><span style=\"font-weight: 400\">La <\/span><b>plataforma colaborativa \u201ctodo en uno\u201d<\/b><span style=\"font-weight: 400\">, como nos gusta llamarla, dedicada a las franquicias, cuenta ahora con m\u00e1s de 250 ense\u00f1as en 100 pa\u00edses y 5 continentes. Son m\u00e1s de 300 000 usuarios diarios y un total de 6 idiomas disponibles en Cerca, antes conocida como Franchise On Cloud.<\/span><\/p><p class=\"translation-block\"><span style=\"font-weight: 400\">Estamos orgullosos de nuestras colaboraciones y de nuestros clientes, a quienes tenemos la suerte de acompa\u00f1ar en su b\u00fasqueda de crecimiento. Seg\u00fan una <\/span><span style=\"font-weight: 400\">encuesta anual realizada en el marco de la renovaci\u00f3n de nuestra certificaci\u00f3n ISO 9001, hemos obtenido m\u00e1s del <\/span><a href=\"https:\/\/cerca.io\/es\/testimonios-de-clientes\/\" target=\"_self\"><span style=\"font-weight: 400\"><span style=\"text-decoration: underline;color: #1284e0\">98 % de satisfacci\u00f3n de los clientes<\/span>.<\/span><\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4e9d30c elementor-widget elementor-widget-heading\" data-id=\"4e9d30c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">El Informe de Desarrollo de la Franquicia 2022, para empezar bien el a\u00f1o\u00a0<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c1429e6 elementor-widget elementor-widget-text-editor\" data-id=\"c1429e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\"><span style=\"font-weight: 400\">El a\u00f1o pasado tambi\u00e9n comenz\u00f3 con cifras, ya que sent\u00edamos que nos faltaban datos sobre el sector de la franquicia. Gracias a nuestros a\u00f1os de experiencia, est\u00e1bamos en una posici\u00f3n ideal para crear el <\/span><span style=\"text-decoration: underline;color: #1284e0\"><a style=\"color: #1284e0\" href=\"https:\/\/cerca.io\/es\/informe-sobre-el-desarrollo-de-la-franquicia-2022\/\" target=\"_self\"><b>Franchise Development Report<\/b><\/a><\/span><span style=\"font-weight: 400\"> en colaboraci\u00f3n con <\/span><span style=\"text-decoration: underline;color: #1284e0\"><a style=\"color: #1284e0\" href=\"https:\/\/everfruitdigital.com\/fr\/\" rel=\"nofollow noopener\" target=\"_blank\"><span style=\"font-weight: 400\">EverFruit Digital<\/span><\/a><\/span><span style=\"font-weight: 400\">.<\/span><\/p><p><span style=\"font-weight: 400;\">El seminario web sigue disponible, al igual que la encuesta. Continuamos analizando el comportamiento de los consumidores para ofrecer el servicio m\u00e1s adaptado posible a las necesidades de los franquiciados y franquiciadores, especialmente en lo que respecta al reclutamiento de candidatos a la franquicia.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ada682b elementor-widget elementor-widget-heading\" data-id=\"ada682b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ferias y foros de franquicias\u00a0<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2784749 elementor-widget elementor-widget-text-editor\" data-id=\"2784749\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\"><span style=\"font-weight: 400\">Cada a\u00f1o se celebran dos grandes eventos que re\u00fanen a todos los actores del sector de la franquicia. El primero tiene lugar en Par\u00eds: la <\/span><span style=\"text-decoration: underline;color: #1284e0\"><a style=\"color: #1284e0;text-decoration: underline\" href=\"https:\/\/www.franchiseparis.com\/\" rel=\"nofollow noopener\" target=\"_blank\"><b>Franchise<\/b> <b>Expo<\/b><\/a><\/span><span style=\"font-weight: 400\"> es una verdadera plataforma de encuentro entre emprendedores. Durante cuatro d\u00edas, el ecosistema franc\u00e9s e internacional de la franquicia se re\u00fane en Franchise Expo Paris. El segundo, el <\/span><span style=\"text-decoration: underline;color: #1284e0\"><a style=\"color: #1284e0\" href=\"https:\/\/www.lyon-franchise.com\/exposer\/\" rel=\"nofollow noopener\" target=\"_blank\"><b>Forum Franchise<\/b><\/a><\/span><span style=\"font-weight: 400\"> en octubre en Lyon, re\u00fane a m\u00e1s de 160 ense\u00f1as que desean acelerar su desarrollo reclutando nuevos franquiciados. Este evento est\u00e1 dirigido principalmente a los franquiciadores, las redes comerciales organizadas y los expertos del sector de la franquicia. Nos alegr\u00f3 haber podido conocer all\u00ed a los franquiciadores y a nuestros clientes, y presentarles nuestra soluci\u00f3n.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8fd1f80 elementor-widget elementor-widget-heading\" data-id=\"8fd1f80\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Una aplicaci\u00f3n m\u00f3vil para franquiciadores y franquiciados<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4a8fdd6 elementor-widget elementor-widget-text-editor\" data-id=\"4a8fdd6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Una nueva versi\u00f3n de nuestra aplicaci\u00f3n m\u00f3vil est\u00e1 disponible desde este a\u00f1o. Incluye todas las funciones necesarias para comunicarse dentro de la red en el d\u00eda a d\u00eda. Disponible para Android y iPhone, permite tener toda la red al alcance de la mano. Accede a todas las noticias con comentarios y \u201cme gusta\u201d, al directorio interactivo, a la mensajer\u00eda, a los grupos de trabajo y a las notificaciones, \u00a1e incluso a las auditor\u00edas y los informes de visita desde este verano!<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c37bd28 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"c37bd28\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3e7113b\" data-id=\"3e7113b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-12977b1 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"12977b1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-bob\" href=\"https:\/\/cerca.io\/es\/essai-gratuit-foc\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Venga a descubrir Cerca<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6403ada elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"6403ada\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8a7949f\" data-id=\"8a7949f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8e466bc elementor-widget elementor-widget-heading\" data-id=\"8e466bc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Marketing digital local integrado en el software de gesti\u00f3n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-32fe45e elementor-widget elementor-widget-text-editor\" data-id=\"32fe45e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">El a\u00f1o contin\u00faa, y nuestras inversiones tambi\u00e9n, siempre con el objetivo de acompa\u00f1ar a nuestros clientes en su marketing local, as\u00ed como en la comunicaci\u00f3n dentro de su propia red de franquicias. Hacemos un repaso de las distintas funcionalidades implementadas a lo largo del a\u00f1o pasado:\u00a0<\/span><\/p><h3><strong>Enfoque en el marketing local con la colaboraci\u00f3n Cerca x Mobilosoft\u00a0<\/strong><\/h3><p class=\"translation-block\"><a href=\"https:\/\/mobilosoft.com\/\" rel=\"nofollow noopener\" target=\"_blank\"><span style=\"font-weight: 400\">Mobilosoft<\/span><\/a><span style=\"font-weight: 400\"> completa la oferta de servicios de Cerca en marketing digital local. Permite generar tr\u00e1fico web-to-store y responde al hecho de que casi el 80\u2009% de los consumidores que realizan una b\u00fasqueda local visitan una tienda en un radio de 8 km (<\/span><a href=\"https:\/\/www.hubspot.fr\/statistiques-marketing\" rel=\"nofollow noopener\" target=\"_blank\"><span style=\"font-weight: 400\">Hubspot Marketing Statistics 2021<\/span><\/a><span style=\"font-weight: 400\">). Este acuerdo refuerza la oferta de formaci\u00f3n y ofrece a las redes de franquicias y a sus franquiciados una plataforma colaborativa de marketing digital para organizar y gestionar mejor su reputaci\u00f3n online.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9c28de3 elementor-widget elementor-widget-heading\" data-id=\"9c28de3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Comunicaci\u00f3n dentro de la red de franquicias\u00a0<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e48fcb0 elementor-widget elementor-widget-text-editor\" data-id=\"e48fcb0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\"><span style=\"font-weight: 400\">La gesti\u00f3n de la red y la actividad diaria de los animadores se ha simplificado gracias a nuestras nuevas funcionalidades de comunicaci\u00f3n dentro de la red. Las <\/span><b>noticias<\/b><span style=\"font-weight: 400\"> ahora pueden clasificarse por establecimiento, los <\/span><b>informes de visita<\/b><span style=\"font-weight: 400\"> pueden duplicarse a partir de un informe existente sin perder los comentarios ni el seguimiento. Adem\u00e1s, al establecer <\/span><b>planes de acci\u00f3n<\/b><span style=\"font-weight: 400\"> durante un informe de visita, una nueva pesta\u00f1a permite verificar si ya hay un plan de acci\u00f3n en curso, evitando as\u00ed duplicados. En cuanto a la cartograf\u00eda, ahora es posible <\/span><b>fusionar las zonas de influencia<\/b><span style=\"font-weight: 400\"> de un establecimiento, y los marcadores de ubicaci\u00f3n tambi\u00e9n pueden hacerse invisibles.<\/span><\/p><p><span style=\"font-weight: 400;\">Estas nuevas funcionalidades agilizan el uso de la plataforma y facilitan el trabajo de los responsables de red.<\/span><\/p><h3><strong>\u00a1Los eventos est\u00e1n cambiando!\u00a0<\/strong><\/h3><p class=\"translation-block\"><span style=\"font-weight: 400\">Novedad tambi\u00e9n este a\u00f1o: <\/span><b>Zoom<\/b><span style=\"font-weight: 400\"> ya est\u00e1 disponible para realizar videoconferencias, al igual que <strong>Google Meet<\/strong>. Despu\u00e9s de <\/span><b>Teams<\/b><span style=\"font-weight: 400\"> y <\/span><b>GoToMeeting,<\/b><span style=\"font-weight: 400\"> ahora es posible realizar videollamadas a trav\u00e9s de las conocidas plataformas Zoom y Google Meet directamente desde Cerca.<\/span><\/p><p class=\"translation-block\"><span style=\"font-weight: 400\">Adem\u00e1s, desde este a\u00f1o, solo se necesita un correo electr\u00f3nico en lugar de dos como antes: el primer correo ya contiene el enlace a la videoconferencia y tambi\u00e9n est\u00e1 disponible en el evento de su calendario.<\/span><b> \u00a1Con un solo clic, puede unirse a la reuni\u00f3n<\/b><span style=\"font-weight: 400\">!<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-97de966 elementor-widget elementor-widget-heading\" data-id=\"97de966\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Repaso a las principales tendencias de consumo de 2022<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6519384 elementor-widget elementor-widget-text-editor\" data-id=\"6519384\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\"><span style=\"font-weight: 400\">El consumidor realiza primero su b\u00fasqueda en l\u00ednea antes de convertir eventualmente en local, como mencionamos <\/span><span style=\"text-decoration: underline;color: #1284e0\"><a style=\"color: #1284e0\" href=\"https:\/\/cerca.io\/es\/tendances-consommateurs-2022-2023\/\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400\">en este art\u00edculo<\/span><\/a><span style=\"font-weight: 400\">: las <\/span><a style=\"color: #1284e0\" href=\"https:\/\/www.thinkwithgoogle.com\/intl\/fr-fr\/insights\/tendances-consommateurs\/marketeurs-liste-lectures-aout\/?utm_medium=email&amp;utm_source=d-content-alert-visual&amp;utm_team=twg-fr&amp;utm_campaign=TwG-FR-CAV-2022-08-09-August-readings-Knak&amp;utm_content=cta-btn&amp;mkt_tok=MTcyLUdPUC04MTEAAAGGIXPzdSGL2NGaPXpRLzLKzacxPXASXZEuPRuveva0tD6DYWQ5mqXubklVxp7eZ6AyYYj8O86lrNDvuktn4i8QEDwD6KZ_MBVwgyoU4XOwOtQgXQ\" rel=\"nofollow noopener\" target=\"_blank\"><span style=\"font-weight: 400\">b\u00fasquedas del tipo \u201cabierto ahora cerca de m\u00ed\u201d<\/span><\/a><\/span><span style=\"font-weight: 400\"> han aumentado en m\u00e1s de <\/span><b>+400% en un a\u00f1o en todo el mundo.<\/b><\/p><p class=\"translation-block\"><span style=\"font-weight: 400\">Las compras son cada vez m\u00e1s omnicanal: redes sociales, web, aplicaciones, boletines, entre otros. Sin embargo, el hecho es que los consumidores buscan sobre todo <\/span><b>valor a\u00f1adido<\/b><span style=\"font-weight: 400\">. Analizan detenidamente las <\/span><b>ofertas<\/b><span style=\"font-weight: 400\"> y las <\/span><b>promociones<\/b><span style=\"font-weight: 400\">, adem\u00e1s de prestar atenci\u00f3n a los valores de la empresa para verificar si est\u00e1n alineados con los suyos. Por \u00faltimo, pero no menos importante, en las redes sociales, los microinfluencers est\u00e1n en auge, y los videos cortos con mucho valor a\u00f1adido est\u00e1n convirtiendo cada vez m\u00e1s. Dicho esto, entre todas las tendencias, una permanece inmutable: la posici\u00f3n cero en el SEO local sigue siendo el motor m\u00e1s eficaz.<\/span><\/p><p class=\"translation-block\"><span style=\"font-weight: 400\">Para seguir las <\/span><b>tendencias de los consumidores<\/b><span style=\"font-weight: 400\"> y <\/span><b>activar el marketing local<\/b><span style=\"font-weight: 400\">, tambi\u00e9n hemos lanzado una colaboraci\u00f3n con DeepReach. Las zonas de captaci\u00f3n est\u00e1n predefinidas, lo que permite activar un conjunto de grupos de anuncios digitales locales adaptados a las necesidades de cada franquiciado.<\/span><\/p><p><b>En resumen, estamos muy contentos con el a\u00f1o que acaba de terminar y tenemos muchas ganas de presentarles nuestros proyectos para 2023.<\/b><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2ef6256 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"2ef6256\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-162c0bb\" data-id=\"162c0bb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9a0dd30 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"9a0dd30\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-bob\" href=\"https:\/\/cerca.io\/es\/essai-gratuit-foc\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Prueba Cerca gratis y descubre todas nuestras funciones.<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b2bc89c elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"b2bc89c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-44bddcd\" data-id=\"44bddcd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2d8f982 elementor-widget elementor-widget-heading\" data-id=\"2d8f982\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Estos art\u00edculos pueden ser de su inter\u00e9s: <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-57b796c elementor-grid-2 elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-posts--thumbnail-top elementor-widget elementor-widget-posts\" data-id=\"57b796c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;classic_columns&quot;:&quot;2&quot;,&quot;classic_masonry&quot;:&quot;yes&quot;,&quot;classic_columns_tablet&quot;:&quot;2&quot;,&quot;classic_columns_mobile&quot;:&quot;1&quot;,&quot;classic_row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:35,&quot;sizes&quot;:[]},&quot;classic_row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;classic_row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"posts.classic\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-posts-container elementor-posts elementor-posts--skin-classic elementor-grid\">\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-24419 post type-post status-publish format-standard has-post-thumbnail hentry category-non-classe-fr tag-en tag-es tag-fr\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/cerca.io\/es\/simplificar-tu-ecosistema-digital-en-4-pasos\/\" tabindex=\"-1\">\n\t\t\t<div class=\"elementor-post__thumbnail\"><img decoding=\"async\" width=\"1747\" height=\"720\" src=\"https:\/\/cerca.io\/wp-content\/uploads\/2026\/07\/Article.png\" class=\"attachment-full size-full wp-image-24461\" alt=\"\" srcset=\"https:\/\/cerca.io\/wp-content\/uploads\/2026\/07\/Article.png 1747w, https:\/\/cerca.io\/wp-content\/uploads\/2026\/07\/Article-300x124.png 300w, https:\/\/cerca.io\/wp-content\/uploads\/2026\/07\/Article-1024x422.png 1024w, https:\/\/cerca.io\/wp-content\/uploads\/2026\/07\/Article-768x317.png 768w, https:\/\/cerca.io\/wp-content\/uploads\/2026\/07\/Article-1536x633.png 1536w, https:\/\/cerca.io\/wp-content\/uploads\/2026\/07\/Article-18x7.png 18w\" sizes=\"(max-width: 1747px) 100vw, 1747px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-24356 post type-post status-publish format-standard has-post-thumbnail hentry category-non-classe-fr tag-en tag-es tag-fr\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/cerca.io\/es\/brief-equipo-7-minutos-coordinacion\/\" tabindex=\"-1\">\n\t\t\t<div class=\"elementor-post__thumbnail\"><img decoding=\"async\" width=\"1746\" height=\"720\" src=\"https:\/\/cerca.io\/wp-content\/uploads\/2026\/06\/Miniature-Blog-2.png\" class=\"attachment-full size-full wp-image-24361\" alt=\"\" srcset=\"https:\/\/cerca.io\/wp-content\/uploads\/2026\/06\/Miniature-Blog-2.png 1746w, https:\/\/cerca.io\/wp-content\/uploads\/2026\/06\/Miniature-Blog-2-300x124.png 300w, https:\/\/cerca.io\/wp-content\/uploads\/2026\/06\/Miniature-Blog-2-1024x422.png 1024w, https:\/\/cerca.io\/wp-content\/uploads\/2026\/06\/Miniature-Blog-2-768x317.png 768w, https:\/\/cerca.io\/wp-content\/uploads\/2026\/06\/Miniature-Blog-2-1536x633.png 1536w, https:\/\/cerca.io\/wp-content\/uploads\/2026\/06\/Miniature-Blog-2-18x7.png 18w\" sizes=\"(max-width: 1746px) 100vw, 1746px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Une belle ann\u00e9e vient de s\u2019\u00e9couler et nous avons beaucoup de projets pour 2023\u202f! Avant de se lancer plein d&rsquo;ambition en 2023, nous jugeons qu\u2019il est toujours bon de prendre du recul sur l\u2019ann\u00e9e pass\u00e9e. En route pour une r\u00e9trospective de 2022. Notre ann\u00e9e en chiffres\u00a0 La plateforme collaborative \u201ctout-en-une\u201d comme nous aimons le dire, r\u00e9serv\u00e9e aux franchises, compte d\u00e9sormais plus de 250 enseignes \u00e0 travers 100 pays, sur 5 continents. Cela fait plus de 300 000 utilisateurs quotidiens, et un total de 6 langues disponibles sur Cerca ex Franchise On Cloud. Nous sommes fiers de nos collaborations et de nos clients, que nous avons la chance d\u2019assister dans leur qu\u00eate de croissance. Selon une enqu\u00eate annuelle r\u00e9alis\u00e9e dans le cadre du renouvellement de notre certification ISO 9001, nous avons r\u00e9colt\u00e9 plus de 98 % de satisfaction client.\u00a0 Le Franchise Development Report 2022, pour bien commencer l\u2019ann\u00e9e\u00a0 L\u2019ann\u00e9e derni\u00e8re avait commenc\u00e9 en chiffre \u00e9galement, puisque nous avions le sentiment\u00a0 que nous manquions de datas sur le secteur de la Franchise. Gr\u00e2ce \u00e0 nos ann\u00e9es d\u2019exp\u00e9riences, nous \u00e9tions tr\u00e8s bien plac\u00e9s pour cr\u00e9er le Franchise Development Report en partenariat avec EverFruit Digital. Le webinaire est toujours disponible, ainsi que l\u2019enqu\u00eate. Nous continuons d&rsquo;analyser les comportements consommateurs afin de fournir le service le plus adapt\u00e9 possible aux besoins des franchis\u00e9s et des franchiseurs, notamment en mati\u00e8re de recrutement de candidats \u00e0 la franchise. Les Salons et Forums de la Franchise\u00a0 Annuellement ont lieu deux grands \u00e9v\u00e9nements qui r\u00e9unissent tous les acteurs du secteur de la franchise. Le premier a lieu \u00e0 Paris, la Franchise Expo \u200b\u200best une v\u00e9ritable plateforme de rencontre entre entrepreneurs, pendant 4 jours l\u2019\u00e9cosyst\u00e8me de la Franchise fran\u00e7ais et mondial se retrouve sur Franchise Expo Paris. Le deuxi\u00e8me, le Forum Franchise en octobre \u00e0 Lyon, r\u00e9unit plus de 160 enseignes qui souhaitent acc\u00e9l\u00e9rer leur d\u00e9veloppement en recrutant de nouveaux franchis\u00e9s. Ce salon s\u2019adresse prioritairement aux franchiseurs, aux enseignes du commerce organis\u00e9 et aux experts du secteur de la franchise. Nous sommes ravis d\u2019avoir pu y rencontrer les franchiseurs et nos clients, et de leur avoir expos\u00e9 notre solution. Une application mobile pour les franchiseurs et les franchis\u00e9s Une nouvelle version de notre application mobile est disponible depuis cette ann\u00e9e. Elle poss\u00e8de toutes les fonctionnalit\u00e9s du quotidien pour communiquer au sein du r\u00e9seau. Disponible sur Android et iPhone, elle permet d\u2019avoir son r\u00e9seau \u00e0 port\u00e9e de main. Cela passe par toutes les actualit\u00e9s avec commentaires et likes, l\u2019annuaire interactif, la messagerie, les groupes de travail et notifications, et m\u00eame les audits et rapports de visite depuis cet \u00e9t\u00e9 ! Venez d\u00e9couvrir Cerca Le marketing digital local int\u00e9gr\u00e9 au logiciel de gestion L\u2019ann\u00e9e continue et nos investissements aussi, toujours dans une volont\u00e9 d\u2019accompagner nos clients dans leur marketing local, mais aussi dans la communication au sein m\u00eame du r\u00e9seau de franchise. Retour sur les diff\u00e9rentes fonctionnalit\u00e9s impl\u00e9ment\u00e9es au cours de l\u2019ann\u00e9e pass\u00e9e :\u00a0 Focus marketing local avec le partenariat Cerca x Mobilosoft\u00a0 Mobilosoft vient compl\u00e9ter l\u2019offre de service de Cerca sur le marketing digital local. Elle permet de g\u00e9n\u00e9rer du trafic web-to-store, et r\u00e9pond au constat que\u00a0 pr\u00e8s de 80\u2009% des consommateurs ayant effectu\u00e9 une recherche locale ont visit\u00e9 un magasin dans un rayon de 8 km (Hubspot Marketing Statistics 2021). Elle vient consolider l\u2019offre de formation, et propose une plateforme collaborative de marketing digital aux r\u00e9seaux de franchises et leurs franchis\u00e9s, pour organiser et g\u00e9rer au mieux leur e-r\u00e9putation.\u00a0 La communication au sein du r\u00e9seau de franchise\u00a0 La vie du r\u00e9seau et celle des animateurs a \u00e9t\u00e9 simplifi\u00e9e gr\u00e2ce \u00e0 nos nouvelles fonctionnalit\u00e9s de communication au sein du r\u00e9seau. Les actualit\u00e9s peuvent d\u00e9sormais \u00eatre class\u00e9es par implantation, les rapports de visite peuvent \u00eatre dupliqu\u00e9s \u00e0 partir d&rsquo;un rapport d\u00e9j\u00e0 existant, sans pour autant perdre les commentaires et le suivi. Aussi, pour mettre en place les plans d\u2019action lors d&rsquo;un rapport de visite, un nouvel onglet existe qui permet de v\u00e9rifier si un plan d\u2019action est d\u00e9j\u00e0 en cours, et \u00e9vite ainsi les doublons. Au niveau de la cartographie, on peut dor\u00e9navant fusionner les zones de chalandise pour une implantation. Le marqueur des implantations peut aussi \u00eatre invisible.\u00a0 Ces nouvelles fonctionnalit\u00e9s fluidifient l\u2019utilisation de la plateforme et facilitent le travail des animateurs r\u00e9seau. Les \u00e9v\u00e9nements changent !\u00a0 Nouveaut\u00e9 aussi cette ann\u00e9e : Zoom est \u00e0 pr\u00e9sent disponible pour effectuer des visioconf\u00e9rences, tout comme Google Meet. Apr\u00e8s Teams et GoToMeeting, il est d\u00e9sormais possible de faire des visios avec les c\u00e9l\u00e8bres plateformes Zoom et Google Meet via Cerca.\u00a0 Par ailleurs, depuis cette ann\u00e9e, un seul mail suffit, au lieu de deux auparavant, le premier mail contient d\u00e9j\u00e0 le lien pour la visioconf\u00e9rence, et sera aussi disponible sur l\u2019\u00e9v\u00e9nement dans votre calendrier. En un clic, vous rejoignez la visio ! Retour sur les grandes tendances consommateurs de 2022 Le consommateur va effectuer sa recherche en ligne avant d\u2019\u00e9ventuellement convertir en local, comme nous le disions dans cet article : les requ\u00eates de type \u00ab ouvert maintenant \u00e0 proximit\u00e9 \u00bb ont bondi de plus de + 400 % sur un an \u00e0 travers le monde. Le shopping est de plus en plus omnicanal : r\u00e9seaux sociaux, web, app, newsletter entre autres. Mais le constat est tel qu\u2019on se rend compte que les consommateurs cherchent surtout de la valeur ajout\u00e9e. Ils scrutent les offres et les promotions, en plus de s\u2019attarder sur les valeurs de l\u2019entreprise, et v\u00e9rifier s\u2019ils sont bien align\u00e9s. Enfin, mais pas des moindres, sur les r\u00e9seaux, les micro-influenceurs ont le vent en poupe, les courtes vid\u00e9os avec beaucoup de valeur ajout\u00e9e convertissent de plus en plus. Ceci dit, de toutes les tendances, une seule ne bouge pas : la position z\u00e9ro en SEO Local reste le levier le plus efficace.\u00a0 Pour suivre les tendances consommateurs et activer le marketing local, nous avons aussi lanc\u00e9 un partenariat avec DeepReach. Les zones de chalandise sont pr\u00e9d\u00e9finies, ce qui permet d\u2019activer un ensemble de groupe de publicit\u00e9s digitales locales, suivant les besoins du franchis\u00e9.\u00a0 En r\u00e9sum\u00e9, nous sommes tr\u00e8s heureux de l\u2019ann\u00e9e qui<\/p>","protected":false},"author":1,"featured_media":19870,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[101,63],"tags":[139],"class_list":["post-15956","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites","category-blog","tag-fr"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/cerca.io\/es\/wp-json\/wp\/v2\/posts\/15956","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cerca.io\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cerca.io\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cerca.io\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cerca.io\/es\/wp-json\/wp\/v2\/comments?post=15956"}],"version-history":[{"count":23,"href":"https:\/\/cerca.io\/es\/wp-json\/wp\/v2\/posts\/15956\/revisions"}],"predecessor-version":[{"id":19873,"href":"https:\/\/cerca.io\/es\/wp-json\/wp\/v2\/posts\/15956\/revisions\/19873"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cerca.io\/es\/wp-json\/wp\/v2\/media\/19870"}],"wp:attachment":[{"href":"https:\/\/cerca.io\/es\/wp-json\/wp\/v2\/media?parent=15956"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cerca.io\/es\/wp-json\/wp\/v2\/categories?post=15956"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cerca.io\/es\/wp-json\/wp\/v2\/tags?post=15956"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}